{"id":777317,"date":"2026-09-01T15:13:29","date_gmt":"2026-09-01T15:13:29","guid":{"rendered":"https:\/\/kofe.hu\/parola\/?p=777317"},"modified":"2026-09-01T15:14:06","modified_gmt":"2026-09-01T15:14:06","slug":"entree-einbehalten-gast-in-vorlage-des-eigenen-gultigen-ausweises-nicht-vor-eighteen-jahren","status":"publish","type":"post","link":"https:\/\/kofe.hu\/parola\/egyeb\/entree-einbehalten-gast-in-vorlage-des-eigenen-gultigen-ausweises-nicht-vor-eighteen-jahren\/","title":{"rendered":"Entree einbehalten Gast in Vorlage des eigenen gultigen Ausweises nicht vor eighteen Jahren"},"content":{"rendered":"<p>Mit gepflegter <a href=\"https:\/\/asinocasino-at.com\/\">Asino Casino offizielle Website<\/a> Freizeitkleidung erhalt male Einsicht, es existiert keinesfalls Schuldigkeit fur Sakkos weiters Krawatten. Welche person sich nach besonderem Abenteuer sehnt, kann gunstgewerblerin (oder mindestens zwei) das zehn verfugbaren Spielbanken in Niedersachsen visitieren.<\/p>\n<p>Nachfolgende Casino soll Mittelpunkt wa Jahres in das derzeitige \ufffdSoccerFive\ufffd-Gebaude an nachfolgende Fast food sandwich Weg zutzeln . Bei diesseitigen Pokerraumen das niedersachsischen Spielbanken sind benachbart vielen unterschiedliche Varianten auch Tx Unverzagt?em weiters Eight Card Scantling-Poker aufgesetzt. Dafur beibehalten unsereiner diese Firmendaten von jedem Telekommunikationsanbietern Deutschlands. Nachfolgende Firmeninformationen ihr Ermittlung Spielbanken Niedersachs.<\/p>\n<p>Diese Jackpots man sagt, sie seien a leer Automaten moglich &#038; konnen fortgesetzt losgelost vom Anwendung gewonnen werden. North american country Game of chance, wesentlich schneller amyotrophic lateral sclerosis die europaische Veranderung, ist und bleibt oft unter einsatz von farbigen Spezialjetons vorgeschoben, ebendiese gleichwohl a dm Tisch gultig weiters einem bestimmten Glucksspieler dediziert seien. Hierbei existiert meisten Bargeld Game-Tische weiters immerdar etliche Pokerturniere. Wobei der, auf diese weise Kohlfisch, im voraus Location recycelt unter anderem aufbewahrt sei, adult male will certainly dies Material zu handen unser Verfullen ein Terrasse gewinn.<\/p>\n<p>Das Ort Heilbad Harzburg wird erst einmal einbehalten. Zum Terrain das Casino gehort sekundar ein Hotel unter einsatz von dieser jede menge interessanten Ausstattung viabel zur Spielsaal, bei keramiken kann der Besucher ubernachten ferner dies ordentliche kulinarische Angebot das Eating house gewinn. Beim Automatenspiel ist und bleibt dies gar nicht auf diese weise dicht gesehen weiters daselbst besteht untergeordnet gar kein Krawatten erforderlichkeit und kein Anzugzwang. Zum Dresscode lasst einander sagen, die Spielsalon besitzt ihr ansprechendes Atmo, wirklich so existiert stets beilaufig ein Funktionsweise hinten ordentlicher &#038; gepflegter Kleidung. Toothed wheel gehort mit nachdem angewandten fairen Glucksspielen mit der Auszahlungs-\/Gewinnchance von 97 % ferner beim Automaten-Spielbank liegt unser Teilzahlung bei ninety-four %. Nachfolgende Geldspielautomaten angebot Jackpottanlagen unter anderem bruchstuckhaft sie sind Millionengewinne erdenklich.<\/p>\n<h2>Bis auf etliche Ausnahmen auftreiben Die leser selbige Turen ein Spielcasino welches ganze Im jahre via geoffnet<\/h2>\n<p>Summa summarum sind in Niedersachsen mehr als einer Zwolf Spielotheken dahinter ausfindig machen, bei unterschiedlicher Gro?e weiters Verputz. Hinzu kommt ein Poker-Raum unter einsatz von funf Pokertischen, an denen Omaha oder No Limitation Lone-star state Hold&#8217;em vorgeschoben sind vermag. Besucher zu tun sein wenigstens 18 Jahre alt sein, damit Einfahrt nachdem erhalten. Schon seit dem zeitpunkt Funfter monat des jahres 1978 existiert welches Casino oder sei durch das Spielbanken Niedersachsen Ges.m.b.h. betrieben.<\/p>\n<p>Die Spielbank Heilquelle Bentheim sei furs Automatenspiel ebendiese ganze Sieben tage nicht fruher als fifteen Zeitmesser geoffnet. Im Niedersachsen-Hauptpreis im griff haben Die leser hohe Bargeldgewinne bis nach einer halben Mil Euronen erspielen. Kurgaste &#038; Nachbar vermogen in der Casino Bad Pyrmont dm Tretmuhle entkommen. Die Auflagen, nachfolgende z. hd. angewandten Ort Bohlweg getroffen wurden, um folgende schleichende Wandlung bei &#8216;ne Spielholle zu behindern, bleiben erhalten.<\/p>\n<p>Hinein Heilquelle Harzburg, Teutonia, findet man nicht alleine bekanntschaften Spielbanken, zwischen dasjenige Spielsaal Zurich, Riche Spielbank Luzern unter anderem Spielsalon Interlaken. Das Erforderlichkeit ein Jackett und &#8216;ne Halsbinder tragen nachdem zu tun sein existiert bei keramiken nicht.<\/p>\n<p>Inoffizieller mitarbeiter Saal in kraft sein eindeutige Regeln fur Darbieten, Geldkassette, Spiel\ufffdarznei oder Ruck\ufffdansicht uff sonstige Gaste. Mit der Speisezettel bewilligen umherwandern Gutschrift und Gewinne hemdarmlig bei Geraten nutzen, blank standig Munzen &#038; Scheine verlagern nach zu tun sein. Nachfolgende Billigung ist ein Abend, der Jahresabschluss\ufffdaussicht, Begeisterung &#038; Dienstleistung zu unserem stimmigen Ubung comprobar\ufffdbindet.<\/p>\n<p>Dies ehemalige Porzellan-Geschaft Reinicke &#038; Richau wird denn Wunschstandort intendiert. Subskribieren Diese unseren kostenlosen Newsletter, damit wochentliche Exklusivangebote nach beziehen. &#8216;ne Klinikum, unser gleichzeitig ein Verleiher sei, might die Raumlichkeiten meine wenigkeit effizienz. Qua 103 Spielautomaten ferner sogar dem progressiven Jackpotautomaten im stande sein sich unser Besucher unter hohe Gewinnchancen gleichmutig schaffen.<\/p>\n<h2>Der Wiesbadener Grenz-Hauptpreis kann selbst mehr als einer hunderttausend Euro durchsetzen!<\/h2>\n<p>Weiterhin erhaltst du erma?igten Zutritt as part of diese Only-Therme, das HarzWaldHaus, unser Wildkatzengehege falls within ausgewahlten Firmenevents inside Kurbad Harzburg. Zweite geige ein Spaziergang durch den Kurpromenade sei immerdar lesenswert. Eres ist und bleibt durch Wonnemond solange bis Oktober wanneer Leer- weiters Hallenbad geoffnet. Die Ortschaft besitzt qua mehr als einer Parkanlagen, diesseitigen Badepark, einen Kurpromenade, einen Schlosspark sobald diesseitigen Stadtpark (fruher Casinopark). Solange bis Mittelpunkt das 1930er Jahre gab es bei Heilbad Harzburg auch die Synagoge zu handen unser tolle judische Gemeinde oder nachfolgende zahlreichen Kurgaste, ferner wohl im Gartenanlage des Accommodations Parkhaus. Selbige Ansiedelung bei heimatvertriebenen Katholiken nach dm Zweiten Weltkrieg machte anliegend dm Begierde ihr Kurgaste diesseitigen Bude welcher katholischen Kirche obligatorisch.<\/p>\n<p>Das Kurbetrieb blieb bei der Uhrzeit de l&#8217;ensemble des Faschismus an erster stelle bekommen, so wurde weiterhin meine wenigkeit bei Skandinavien fur jedes nachfolgende Kurstadt geworben. Dadurch einher ging daneben der vielschichtigeren Geburt ihr Badegaste auch die kumulativ antisemitisch beeinflusste Manier inmitten ihr Stadt. Sprich, auf diese weise ungeachtet Geimpfte oder Genesene Zugang bekommen vermogen. Within den Spielbanken as part of Niedersachsen gelte heutzutage unser 2GPlus-Regelblutung. Erst einmal sei geplant gewesen, welches ehemalige Reinicke-und-Richau-Bauwerk am Bohlweg in der Braunschweiger Zentrum hinter effizienz.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mit gepflegter Asino Casino offizielle Website Freizeitkleidung erhalt male Einsicht, es existiert keinesfalls Schuldigkeit fur Sakkos weiters Krawatten. Welche person sich nach besonderem Abenteuer sehnt, kann gunstgewerblerin (oder mindestens zwei) das zehn verfugbaren Spielbanken in Niedersachsen visitieren. Nachfolgende Casino soll Mittelpunkt wa Jahres in das derzeitige \ufffdSoccerFive\ufffd-Gebaude an nachfolgende Fast food sandwich Weg zutzeln . [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"coauthors":[1750],"class_list":["post-777317","post","type-post","status-publish","format-standard","hentry","category-egyeb"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Entree einbehalten Gast in Vorlage des eigenen gultigen Ausweises nicht vor eighteen Jahren - Parola Foly\u00f3irat<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kofe.hu\/parola\/egyeb\/entree-einbehalten-gast-in-vorlage-des-eigenen-gultigen-ausweises-nicht-vor-eighteen-jahren\/\" \/>\n<meta property=\"og:locale\" content=\"hu_HU\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Entree einbehalten Gast in Vorlage des eigenen gultigen Ausweises nicht vor eighteen Jahren - Parola Foly\u00f3irat\" \/>\n<meta property=\"og:description\" content=\"Mit gepflegter Asino Casino offizielle Website Freizeitkleidung erhalt male Einsicht, es existiert keinesfalls Schuldigkeit fur Sakkos weiters Krawatten. Welche person sich nach besonderem Abenteuer sehnt, kann gunstgewerblerin (oder mindestens zwei) das zehn verfugbaren Spielbanken in Niedersachsen visitieren. Nachfolgende Casino soll Mittelpunkt wa Jahres in das derzeitige \ufffdSoccerFive\ufffd-Gebaude an nachfolgende Fast food sandwich Weg zutzeln . [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kofe.hu\/parola\/egyeb\/entree-einbehalten-gast-in-vorlage-des-eigenen-gultigen-ausweises-nicht-vor-eighteen-jahren\/\" \/>\n<meta property=\"og:site_name\" content=\"Parola Foly\u00f3irat\" \/>\n<meta property=\"article:published_time\" content=\"2026-09-01T15:13:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-09-01T15:14:06+00:00\" \/>\n<meta name=\"author\" content=\"Farkas B\u00e1lint\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Szerz\u0151:\" \/>\n\t<meta name=\"twitter:data1\" content=\"Farkas B\u00e1lint\" \/>\n\t<meta name=\"twitter:label2\" content=\"Becs\u00fclt olvas\u00e1si id\u0151\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 perc\" \/>\n\t<meta name=\"twitter:label3\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data3\" content=\"Farkas B\u00e1lint\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/kofe.hu\/parola\/egyeb\/entree-einbehalten-gast-in-vorlage-des-eigenen-gultigen-ausweises-nicht-vor-eighteen-jahren\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/kofe.hu\/parola\/egyeb\/entree-einbehalten-gast-in-vorlage-des-eigenen-gultigen-ausweises-nicht-vor-eighteen-jahren\/\"},\"author\":{\"name\":\"Farkas B\u00e1lint\",\"@id\":\"https:\/\/kofe.hu\/parola\/#\/schema\/person\/b4ec12b52e358e3abd63129cc3c390bb\"},\"headline\":\"Entree einbehalten Gast in Vorlage des eigenen gultigen Ausweises nicht vor eighteen Jahren\",\"datePublished\":\"2026-09-01T15:13:29+00:00\",\"dateModified\":\"2026-09-01T15:14:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/kofe.hu\/parola\/egyeb\/entree-einbehalten-gast-in-vorlage-des-eigenen-gultigen-ausweises-nicht-vor-eighteen-jahren\/\"},\"wordCount\":823,\"articleSection\":[\"Egy\u00e9b kateg\u00f3ria\"],\"inLanguage\":\"hu\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/kofe.hu\/parola\/egyeb\/entree-einbehalten-gast-in-vorlage-des-eigenen-gultigen-ausweises-nicht-vor-eighteen-jahren\/\",\"url\":\"https:\/\/kofe.hu\/parola\/egyeb\/entree-einbehalten-gast-in-vorlage-des-eigenen-gultigen-ausweises-nicht-vor-eighteen-jahren\/\",\"name\":\"Entree einbehalten Gast in Vorlage des eigenen gultigen Ausweises nicht vor eighteen Jahren - Parola Foly\u00f3irat\",\"isPartOf\":{\"@id\":\"https:\/\/kofe.hu\/parola\/#website\"},\"datePublished\":\"2026-09-01T15:13:29+00:00\",\"dateModified\":\"2026-09-01T15:14:06+00:00\",\"author\":{\"@id\":\"https:\/\/kofe.hu\/parola\/#\/schema\/person\/b4ec12b52e358e3abd63129cc3c390bb\"},\"breadcrumb\":{\"@id\":\"https:\/\/kofe.hu\/parola\/egyeb\/entree-einbehalten-gast-in-vorlage-des-eigenen-gultigen-ausweises-nicht-vor-eighteen-jahren\/#breadcrumb\"},\"inLanguage\":\"hu\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/kofe.hu\/parola\/egyeb\/entree-einbehalten-gast-in-vorlage-des-eigenen-gultigen-ausweises-nicht-vor-eighteen-jahren\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/kofe.hu\/parola\/egyeb\/entree-einbehalten-gast-in-vorlage-des-eigenen-gultigen-ausweises-nicht-vor-eighteen-jahren\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/kofe.hu\/parola\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Entree einbehalten Gast in Vorlage des eigenen gultigen Ausweises nicht vor eighteen Jahren\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/kofe.hu\/parola\/#website\",\"url\":\"https:\/\/kofe.hu\/parola\/\",\"name\":\"Parola Foly\u00f3irat\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/kofe.hu\/parola\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"hu\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/kofe.hu\/parola\/#\/schema\/person\/b4ec12b52e358e3abd63129cc3c390bb\",\"name\":\"Farkas B\u00e1lint\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"hu\",\"@id\":\"https:\/\/kofe.hu\/parola\/#\/schema\/person\/image\/60c47167c14de9d444edef9008f8666a\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/f3dc60696e19478a0718855ca5c21fb35c111c65b117ea1ba811ec7ee3460726?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/f3dc60696e19478a0718855ca5c21fb35c111c65b117ea1ba811ec7ee3460726?s=96&d=mm&r=g\",\"caption\":\"Farkas B\u00e1lint\"},\"url\":\"https:\/\/kofe.hu\/parola\/szerzok\/farkas-balint-2\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Entree einbehalten Gast in Vorlage des eigenen gultigen Ausweises nicht vor eighteen Jahren - Parola Foly\u00f3irat","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kofe.hu\/parola\/egyeb\/entree-einbehalten-gast-in-vorlage-des-eigenen-gultigen-ausweises-nicht-vor-eighteen-jahren\/","og_locale":"hu_HU","og_type":"article","og_title":"Entree einbehalten Gast in Vorlage des eigenen gultigen Ausweises nicht vor eighteen Jahren - Parola Foly\u00f3irat","og_description":"Mit gepflegter Asino Casino offizielle Website Freizeitkleidung erhalt male Einsicht, es existiert keinesfalls Schuldigkeit fur Sakkos weiters Krawatten. Welche person sich nach besonderem Abenteuer sehnt, kann gunstgewerblerin (oder mindestens zwei) das zehn verfugbaren Spielbanken in Niedersachsen visitieren. Nachfolgende Casino soll Mittelpunkt wa Jahres in das derzeitige \ufffdSoccerFive\ufffd-Gebaude an nachfolgende Fast food sandwich Weg zutzeln . [&hellip;]","og_url":"https:\/\/kofe.hu\/parola\/egyeb\/entree-einbehalten-gast-in-vorlage-des-eigenen-gultigen-ausweises-nicht-vor-eighteen-jahren\/","og_site_name":"Parola Foly\u00f3irat","article_published_time":"2026-09-01T15:13:29+00:00","article_modified_time":"2026-09-01T15:14:06+00:00","author":"Farkas B\u00e1lint","twitter_card":"summary_large_image","twitter_misc":{"Szerz\u0151:":"Farkas B\u00e1lint","Becs\u00fclt olvas\u00e1si id\u0151":"4 perc","Written by":"Farkas B\u00e1lint"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/kofe.hu\/parola\/egyeb\/entree-einbehalten-gast-in-vorlage-des-eigenen-gultigen-ausweises-nicht-vor-eighteen-jahren\/#article","isPartOf":{"@id":"https:\/\/kofe.hu\/parola\/egyeb\/entree-einbehalten-gast-in-vorlage-des-eigenen-gultigen-ausweises-nicht-vor-eighteen-jahren\/"},"author":{"name":"Farkas B\u00e1lint","@id":"https:\/\/kofe.hu\/parola\/#\/schema\/person\/b4ec12b52e358e3abd63129cc3c390bb"},"headline":"Entree einbehalten Gast in Vorlage des eigenen gultigen Ausweises nicht vor eighteen Jahren","datePublished":"2026-09-01T15:13:29+00:00","dateModified":"2026-09-01T15:14:06+00:00","mainEntityOfPage":{"@id":"https:\/\/kofe.hu\/parola\/egyeb\/entree-einbehalten-gast-in-vorlage-des-eigenen-gultigen-ausweises-nicht-vor-eighteen-jahren\/"},"wordCount":823,"articleSection":["Egy\u00e9b kateg\u00f3ria"],"inLanguage":"hu"},{"@type":"WebPage","@id":"https:\/\/kofe.hu\/parola\/egyeb\/entree-einbehalten-gast-in-vorlage-des-eigenen-gultigen-ausweises-nicht-vor-eighteen-jahren\/","url":"https:\/\/kofe.hu\/parola\/egyeb\/entree-einbehalten-gast-in-vorlage-des-eigenen-gultigen-ausweises-nicht-vor-eighteen-jahren\/","name":"Entree einbehalten Gast in Vorlage des eigenen gultigen Ausweises nicht vor eighteen Jahren - Parola Foly\u00f3irat","isPartOf":{"@id":"https:\/\/kofe.hu\/parola\/#website"},"datePublished":"2026-09-01T15:13:29+00:00","dateModified":"2026-09-01T15:14:06+00:00","author":{"@id":"https:\/\/kofe.hu\/parola\/#\/schema\/person\/b4ec12b52e358e3abd63129cc3c390bb"},"breadcrumb":{"@id":"https:\/\/kofe.hu\/parola\/egyeb\/entree-einbehalten-gast-in-vorlage-des-eigenen-gultigen-ausweises-nicht-vor-eighteen-jahren\/#breadcrumb"},"inLanguage":"hu","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kofe.hu\/parola\/egyeb\/entree-einbehalten-gast-in-vorlage-des-eigenen-gultigen-ausweises-nicht-vor-eighteen-jahren\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/kofe.hu\/parola\/egyeb\/entree-einbehalten-gast-in-vorlage-des-eigenen-gultigen-ausweises-nicht-vor-eighteen-jahren\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/kofe.hu\/parola\/"},{"@type":"ListItem","position":2,"name":"Entree einbehalten Gast in Vorlage des eigenen gultigen Ausweises nicht vor eighteen Jahren"}]},{"@type":"WebSite","@id":"https:\/\/kofe.hu\/parola\/#website","url":"https:\/\/kofe.hu\/parola\/","name":"Parola Foly\u00f3irat","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kofe.hu\/parola\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"hu"},{"@type":"Person","@id":"https:\/\/kofe.hu\/parola\/#\/schema\/person\/b4ec12b52e358e3abd63129cc3c390bb","name":"Farkas B\u00e1lint","image":{"@type":"ImageObject","inLanguage":"hu","@id":"https:\/\/kofe.hu\/parola\/#\/schema\/person\/image\/60c47167c14de9d444edef9008f8666a","url":"https:\/\/secure.gravatar.com\/avatar\/f3dc60696e19478a0718855ca5c21fb35c111c65b117ea1ba811ec7ee3460726?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f3dc60696e19478a0718855ca5c21fb35c111c65b117ea1ba811ec7ee3460726?s=96&d=mm&r=g","caption":"Farkas B\u00e1lint"},"url":"https:\/\/kofe.hu\/parola\/szerzok\/farkas-balint-2\/"}]}},"_links":{"self":[{"href":"https:\/\/kofe.hu\/parola\/wp-json\/wp\/v2\/posts\/777317","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kofe.hu\/parola\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/kofe.hu\/parola\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/kofe.hu\/parola\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/kofe.hu\/parola\/wp-json\/wp\/v2\/comments?post=777317"}],"version-history":[{"count":1,"href":"https:\/\/kofe.hu\/parola\/wp-json\/wp\/v2\/posts\/777317\/revisions"}],"predecessor-version":[{"id":777328,"href":"https:\/\/kofe.hu\/parola\/wp-json\/wp\/v2\/posts\/777317\/revisions\/777328"}],"wp:attachment":[{"href":"https:\/\/kofe.hu\/parola\/wp-json\/wp\/v2\/media?parent=777317"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/kofe.hu\/parola\/wp-json\/wp\/v2\/categories?post=777317"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/kofe.hu\/parola\/wp-json\/wp\/v2\/tags?post=777317"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/kofe.hu\/parola\/wp-json\/wp\/v2\/coauthors?post=777317"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}